{"id":2213,"date":"2020-01-09T17:38:02","date_gmt":"2020-01-09T16:38:02","guid":{"rendered":"https:\/\/joieinterieure.com\/?p=2213"},"modified":"2020-01-13T16:15:55","modified_gmt":"2020-01-13T15:15:55","slug":"devenir-responsable-de-soi","status":"publish","type":"post","link":"https:\/\/joieinterieure.com\/index.php\/2020\/01\/09\/devenir-responsable-de-soi\/","title":{"rendered":"Devenir responsable de soi"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jpvaa0mm-74a90d04f1ded27df6ca868183e75c63\">\n.avia-section.av-jpvaa0mm-74a90d04f1ded27df6ca868183e75c63 .av-parallax .av-parallax-inner{\nbackground-repeat:no-repeat;\nbackground-image:url(https:\/\/joieinterieure.com\/wp-content\/uploads\/2020\/01\/Sans-titre-2-1030x1030.png);\nbackground-position:50% 0%;\nbackground-attachment:scroll;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-jpvaa0mm-74a90d04f1ded27df6ca868183e75c63 main_color avia-section-default avia-no-border-styling  avia-builder-el-0  el_before_av_one_full  avia-builder-el-first  avia-full-stretch av-parallax-section avia-bg-style-parallax  container_wrap fullsize'  data-section-bg-repeat='stretch'><div class='av-parallax' data-avia-parallax-ratio='0.3' ><div class='av-parallax-inner main_color avia-full-stretch'><\/div><\/div><div class='container av-section-cont-open' ><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-2213'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jpvacthg-ae6ca640a8795486d1cefce423cf8102\">\n#top .hr.hr-invisible.av-jpvacthg-ae6ca640a8795486d1cefce423cf8102{\nheight:50px;\n}\n<\/style>\n<div  class='hr av-jpvacthg-ae6ca640a8795486d1cefce423cf8102 hr-invisible  avia-builder-el-1  el_before_av_textblock  avia-builder-el-first  '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock  av_inherit_color '   itemprop=\"text\" ><h1 style=\"text-align: center;\"><span style=\"color: #ffffff;\"><strong>Devenir Responsable de Soi<\/strong><\/span><\/h1>\n<\/div><\/section>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jpvacthg-ae6ca640a8795486d1cefce423cf8102\">\n#top .hr.hr-invisible.av-jpvacthg-ae6ca640a8795486d1cefce423cf8102{\nheight:50px;\n}\n<\/style>\n<div  class='hr av-jpvacthg-ae6ca640a8795486d1cefce423cf8102 hr-invisible  avia-builder-el-3  el_after_av_textblock  avia-builder-el-last  '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<\/div><\/div><\/main><!-- close content main element --><\/div><\/div><div id='after_section_1'  class='main_color av_default_container_wrap container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-2213'><div class='entry-content-wrapper clearfix'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jogdkl-67488dea45c329c98b968b57a7606449\">\n.flex_column.av-jogdkl-67488dea45c329c98b968b57a7606449{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-jogdkl-67488dea45c329c98b968b57a7606449 av_one_full  avia-builder-el-4  el_after_av_section  el_before_av_one_full  avia-builder-el-first  first flex_column_div av-zero-column-padding '   ><section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock  '   itemprop=\"text\" ><h3 style=\"text-align: center;\"><strong>Devenir responsable de soi est le plus beau cadeau <\/strong><strong>que l\u2019on peut offrir <\/strong><\/h3>\n<h3 style=\"text-align: center;\"><strong>\u00e0 la plan\u00e8te, au monde et \u00e0 nous-m\u00eame.<\/strong><\/h3>\n<\/div><\/section><\/div><\/p>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-hunc2t-be9e7ba21d7da41201521e4595822f3b\">\n.flex_column.av-hunc2t-be9e7ba21d7da41201521e4595822f3b{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-hunc2t-be9e7ba21d7da41201521e4595822f3b av_one_full  avia-builder-el-6  el_after_av_one_full  el_before_av_one_half  first flex_column_div av-zero-column-padding column-top-margin'   ><section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock  '   itemprop=\"text\" ><h2 style=\"text-align: center;\"><\/h2>\n<p style=\"text-align: center;\">Une nouvelle ann\u00e9e d\u00e9bute, de nouvelles \u00e9nergies se mettent en place, 2019 nous demandait de voir les choses diff\u00e9remment, cette ann\u00e9e nous construisons donc diff\u00e9remment.<\/p>\n<p style=\"text-align: center;\">Alors, je souhaite \u00e0 tous <strong>que cette ann\u00e9e soit port\u00e9e par la Paix Int\u00e9rieure<\/strong>. En effet, ce qui est \u00e0 l\u2019ext\u00e9rieur est le miroir de ce qu\u2019il y a l\u2019int\u00e9rieur. Si chacun d\u2019entre nous se reconnecte \u00e0 lui-m\u00eame, dans la profondeur de son \u00eatre pour laisser jaillir la paix int\u00e9rieure, le changement de ce monde sera spectaculaire.<\/p>\n<p style=\"text-align: center;\">La per-ma-culture a \u00e9t\u00e9 tr\u00e8s r\u00e9v\u00e9latrice pour moi, et j\u2019ai compris une chose en 2019, c\u2019est que le meilleur des potagers que l\u2019on peut offrir au monde, c\u2019est bien notre potager int\u00e9rieur.<\/p>\n<p style=\"text-align: center;\">Nous cherchons bien souvent \u00e0 vouloir agir vers l\u2019ext\u00e9rieur, envoyer de l\u2019amour pour autrui, envoyer de l\u2019Amour \u00e0 la plan\u00e8te, \u00e0 un mouvement etc. Mais <strong>la cl\u00e9 de tout<\/strong> est avant toutes choses de s\u2019envoyer de l<strong>\u2019Amour \u00e0 soi-m\u00eame<\/strong>. Si nous sentons une personne ou une situation qui nous fait monter de l\u2019\u00e9motionnel en nous, cela appartient \u00e0 notre r\u00e9alit\u00e9 propre. A une blessure personnelle, une m\u00e9moire personnelle qui nous fait ressentir telles situations d\u00e9sagr\u00e9ables. Alors c\u2019est en nous-m\u00eame que nous devons aller panser cela avec un rem\u00e8de\u00a0: <strong>l\u2019<a href=\"https:\/\/joieinterieure.com\/index.php\/energeticienne-savigny-sur-orge-essonne-2\/\">Amour<\/a> pour soi.<\/strong><\/p>\n<\/div><\/section><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gcy911-b9cf4520876884fb6c62abdac76d6f36\">\n.flex_column.av-gcy911-b9cf4520876884fb6c62abdac76d6f36{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-gcy911-b9cf4520876884fb6c62abdac76d6f36 av_one_half  avia-builder-el-8  el_after_av_one_full  el_before_av_one_half  first flex_column_div av-zero-column-padding column-top-margin'   ><section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock  '   itemprop=\"text\" ><p style=\"text-align: center;\">Tel un Phoenix c\u2019est <strong>accueillir ce qui est<\/strong>, et laisser la transmutation se faire en nous afin de trouver ce <strong>graal<\/strong> qui est la paix int\u00e9rieure, la s\u00e9r\u00e9nit\u00e9. Cela permettra \u00e0 toutes formes ext\u00e9rieures de pouvoir s\u2019en inspirer.<\/p>\n<p style=\"text-align: center;\">On donne ainsi droit \u00e0 l\u2019autre de <strong>s\u2019Aimer<\/strong> lui-m\u00eame, de pacifier toutes ses \u00e9motions int\u00e9rieures. On ne peut pas changer l\u2019autre, et on ne peut pas donner la responsabilit\u00e9 \u00e0 l\u2019autre de ce qui se passe en nous. Nous pouvons vivre une seule et m\u00eame situation \u00e0 plusieurs, chacun aura son v\u00e9cu et interpr\u00e9tera ce qui se passe selon ce qui se passe en lui-m\u00eame.<\/p>\n<p style=\"text-align: center;\">C\u2019est \u00e0 chacun de retrouver son pouvoir personnel, <b>\u00ab\u00a0Connais-toi, toi-m\u00eame et tu conna\u00eetra l\u2019univers et les Dieux\u00a0\u00bb<\/b>, oui tout se passe en soi.<\/p>\n<p style=\"text-align: center;\">Alors avant d\u2019envoyer de l\u2019amour aux autres penser avant tout \u00e0 vous envoyer de l\u2019amour \u00e0 vous-m\u00eame, car c\u2019est ainsi que vous pourrez aider les autres.<\/p>\n<\/div><\/section><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-es22gl-730f6ddf3c8c958e48c8e55443db8312\">\n.flex_column.av-es22gl-730f6ddf3c8c958e48c8e55443db8312{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-es22gl-730f6ddf3c8c958e48c8e55443db8312 av_one_half  avia-builder-el-10  el_after_av_one_half  el_before_av_one_full  flex_column_div av-zero-column-padding column-top-margin'   ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k56xgvw6-4dbb6c37b4f1eb54c7bfedc5bd1e9d05\">\n.avia-image-container.av-k56xgvw6-4dbb6c37b4f1eb54c7bfedc5bd1e9d05 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-k56xgvw6-4dbb6c37b4f1eb54c7bfedc5bd1e9d05 av-styling- avia-align-center  avia-builder-el-11  avia-builder-el-no-sibling  '  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img class='wp-image-2214 avia-img-lazy-loading-not-2214 avia_image' src='https:\/\/joieinterieure.com\/wp-content\/uploads\/2020\/01\/Sans-titre-2-300x300.png' alt='ducrocq amelie' title='Sans titre (2)'  height=\"300\" width=\"300\"  itemprop=\"thumbnailUrl\"  \/><\/div><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-cgydud-3097149ad4aee378ca4079dbea426087\">\n.flex_column.av-cgydud-3097149ad4aee378ca4079dbea426087{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-cgydud-3097149ad4aee378ca4079dbea426087 av_one_full  avia-builder-el-12  el_after_av_one_half  el_before_av_one_half  first flex_column_div av-zero-column-padding column-top-margin'   ><section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock  '   itemprop=\"text\" ><p style=\"text-align: center;\">Lorsqu\u2019on est en paix \u00e0 l\u2019int\u00e9rieur de nous-m\u00eame, nous ne nous laissons plus influencer par les \u00e9nergies environnantes, on arr\u00eate d\u2019<strong>\u00eatre \u00e9ponge<\/strong> de ce qui se passe autour.<\/p>\n<p style=\"text-align: center;\">On est un catalyseur d\u2019<strong>\u00e9nergie positive<\/strong> et on l\u2019offre tout autour de nous. Tel un maillon d\u2019une cha\u00eene, nous pouvons ainsi offrir une \u00e9nergie nouvelle aux autres maillons.<\/p>\n<p style=\"text-align: center;\">Ce c\u00f4t\u00e9 \u00e9ponge, ressort souvent, on voit cela comme une tare d\u2019\u00eatre <strong>empathique<\/strong>, oui ce n\u2019est pas toujours facile de le g\u00e9rer et de le comprendre. Mais quelle force cela repr\u00e9sente\u00a0! Cela signifie que vous arrivez \u00e0 ressentir l\u2019\u00e9motion de l\u2019autre.<\/p>\n<p style=\"text-align: center;\">Il ne s\u2019agit pas de se laisser envahir, mais bien de comprendre que ce que tu ressens, ne t\u2019appartient pas ! C\u2019est ce qui se passe dans son corps \u00e0 lui\/elle\u00a0\u00a0!<\/p>\n<p style=\"text-align: center;\">Je ne prends pas cela personnellement (un des <strong>accords tolt\u00e8ques<\/strong> ;-). Je sais ce qui se passe chez l\u2019autre, ce qui me permet de prendre de la hauteur \u00e0 l\u2019int\u00e9rieur de moi, je me remets dans mon centre, dans ma maison int\u00e9rieure remplie de bienveillance et de paix, ainsi je peux avoir un regard plus haut. Cela t\u2019offre un tableau de ce qui se passe. Ainsi tu offres \u00e0 l\u2019autre le droit de faire de m\u00eame.<\/p>\n<p style=\"text-align: center;\">Par exemple, tu es entre amis, et le ton monte, un conflit commence \u00e0 prendre forme. Tu ressens la col\u00e8re, l\u2019\u00e9nervement en toi. Cette col\u00e8re provient de ta gauche, la tristesse d\u2019en face, l\u2019\u00e9nervement de ta droite et toi tu es au milieu et tu fais \u00e9ponge.<\/p>\n<p style=\"text-align: center;\"><strong>Deux solutions\u00a0:<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Option 1\u00a0: <\/strong><\/p>\n<p style=\"text-align: center;\">Tu te laisses envahir par ces \u00e9motions, tu te mets en col\u00e8re, la situation t\u2019\u00e9nerve et tout cela te rend triste. Le clash se fait entre tous et la soir\u00e9e prend une tournure absolument pas agr\u00e9able. Il y a une amplification qui se fait et cela fait monter la sauce.<\/p>\n<p style=\"text-align: center;\"><strong>Option 2 : <\/strong><\/p>\n<p style=\"text-align: center;\">Tu respires, tu prends de la hauteur sur les \u00e9motions qui sont g\u00e9n\u00e9r\u00e9es en toi, tu acceptes que chacun ait le droit de ressentir telle ou telles \u00e9motions suivant son histoire mais toi, tu as un jardin int\u00e9rieur te permettant d\u2019\u00eatre en paix, en s\u00e9r\u00e9nit\u00e9, tu t\u2019y plonge et tu sors du jeu.<\/p>\n<p style=\"text-align: center;\">Ton \u00e9nergie rayonne autour et comme par magie l\u2019ambiance redescend, la temp\u00e9rance se met en place. Tu as g\u00e9n\u00e9rer une nouvelle dynamique dans la boucle. Je re\u00e7ois ce qui se passe mais je reste calme, je ne suis pas responsable de la gestion \u00e9motionnelle des personnes autour de moi, mais je suis responsable de moi.<\/p>\n<p style=\"text-align: center;\">Alors je peux devenir un exemple de paix et s\u00e9r\u00e9nit\u00e9 pour ceux autour de moi. Je ne rentre pas dans le jeu mais j\u2019en prends conscience pour d\u00e9tendre l\u2019atmosph\u00e8re. On aide ainsi \u00e0 chacun \u00e0 reprendre son pouvoir int\u00e9rieur.<\/p>\n<\/div><\/section><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-bjugw5-58a7f1749f23edcc3ddbe34f011d5c10\">\n.flex_column.av-bjugw5-58a7f1749f23edcc3ddbe34f011d5c10{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-bjugw5-58a7f1749f23edcc3ddbe34f011d5c10 av_one_half  avia-builder-el-14  el_after_av_one_full  el_before_av_one_half  first flex_column_div av-zero-column-padding column-top-margin'   ><section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock  '   itemprop=\"text\" ><p style=\"text-align: center;\">Oui c\u2019est bien mais en application <strong>\u00e7a marche comment<\/strong>.<\/p>\n<p style=\"text-align: center;\">C\u2019est avant toute chose de rep\u00e9rer <strong>les \u00e9motions<\/strong> qui nous traversent\u00a0: elles m\u2019appartiennent \u00e0 moi ou je ressens une \u00e9motion d\u2019une tiers personne\u00a0?<\/p>\n<p style=\"text-align: center;\">Si elles sont \u00e0 moi , elles ne sont pas l\u00e0 par hasard, ce sont de v\u00e9ritables boussoles internes. Une fois les \u00e9motions reconnues, c\u2019est les <strong>accueillir<\/strong> avec <strong>bienveillance<\/strong>. Si elles ont besoin de sortir, on les laissent, pleure autant de temps que n\u00e9cessaire, crie pour faire sortir cette col\u00e8re (en intimit\u00e9 pas sur tous tes proches \ud83d\ude09 prends un coussin et crie dedans), vie ces \u00e9motions qui viennent toquer \u00e0 ta porte.<\/p>\n<p style=\"text-align: center;\">Comprendre d\u2019o\u00f9 vient la racine de ces \u00e9motions n\u00e9cessaire ou pas, \u00e0 toi de voir ce qui sera juste mais soit bienveillant avec toi-m\u00eame et offre toi la <strong>compassion<\/strong> n\u00e9cessaire et l\u2019amour pour l\u2019aider \u00e0 s&rsquo;apaiser. C\u2019est en apaisant nos \u00e9motions que l\u2019on trouve la s\u00e9r\u00e9nit\u00e9 int\u00e9rieure. Et lorsque tu es en lien avec cette s\u00e9r\u00e9nit\u00e9, elle te permet de prendre de la hauteur face aux conflits ext\u00e9rieurs. Et comme nous le disions plus haut, ce qu\u2019il y a \u00e0 l\u2019int\u00e9rieur \u00e9mane \u00e0 l\u2019ext\u00e9rieur.<\/p>\n<\/div><\/section><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-95yovp-d86742f39f5e53b356fb5bc5ef14c164\">\n.flex_column.av-95yovp-d86742f39f5e53b356fb5bc5ef14c164{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-95yovp-d86742f39f5e53b356fb5bc5ef14c164 av_one_half  avia-builder-el-16  el_after_av_one_half  el_before_av_one_full  flex_column_div av-zero-column-padding column-top-margin'   ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k56xt0hc-9cb52574b8f81d08e116a6593462769b\">\n.avia-image-container.av-k56xt0hc-9cb52574b8f81d08e116a6593462769b .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-k56xt0hc-9cb52574b8f81d08e116a6593462769b av-styling- avia-align-center  avia-builder-el-17  avia-builder-el-no-sibling  '  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img class='wp-image-2089 avia-img-lazy-loading-not-2089 avia_image' src='https:\/\/joieinterieure.com\/wp-content\/uploads\/2019\/07\/sommi-h-yb5TjYJ-I-unsplash-1030x687.jpg' alt='ange' title='D\u00e9ployer ses ailes'  height=\"687\" width=\"1030\"  itemprop=\"thumbnailUrl\"  \/><\/div><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-70x779-25f7459803737116690ddb6f55decb54\">\n.flex_column.av-70x779-25f7459803737116690ddb6f55decb54{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-70x779-25f7459803737116690ddb6f55decb54 av_one_full  avia-builder-el-18  el_after_av_one_half  el_before_av_one_full  first flex_column_div av-zero-column-padding column-top-margin'   ><section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock  '   itemprop=\"text\" ><p style=\"text-align: center;\">Devenir responsable de soi est le plus beau cadeau que l\u2019on peut offrir \u00e0 la plan\u00e8te, au monde et \u00e0 nous-m\u00eame.<\/p>\n<p style=\"text-align: center;\">Il n\u2019y a pas de petite action si nous sommes 8 milliards \u00e0 le faire.<\/p>\n<p style=\"text-align: center;\">Accueillir ce qui se passe, prendre le temps de dig\u00e9rer pour transmuter ce qui doit l\u2019\u00eatre afin de laisser jaillir pleinement son Amour. C\u2019est un travail quotidien oui, car ce n\u2019est pas toujours agr\u00e9able d\u2019accepter quelque chose qui a un go\u00fbt amer, qui n\u2019est pas bon. Mais quel cadeau de permettre \u00e0 cela de se transformer en paix int\u00e9rieure.<\/p>\n<p style=\"text-align: center;\">On n\u2019est plus dans la r\u00e9action, on est dans l\u2019int\u00e9gration de ce qui se passe, on prend soin de soi. On n\u2019est pas dans l\u2019effet ping-pong, on sort de ce jeu-l\u00e0.<\/p>\n<p style=\"text-align: center;\">Donc l\u2019id\u00e9e est de <strong>se retrouver<\/strong>, de <strong>se centrer en soi<\/strong> pour <strong>cultiver notre jardin int\u00e9rieur<\/strong> dans <strong>la bienveillance<\/strong>, <strong>la s\u00e9r\u00e9nit\u00e9, la paix et l\u2019Amour<\/strong>.<\/p>\n<p style=\"text-align: center;\">Si nous ne sommes pas en paix \u00e0 l\u2019int\u00e9rieur nos interventions ext\u00e9rieures ne seront pas g\u00e9n\u00e9ratrices de notre volont\u00e9 originelle. Chaque maillon de la cha\u00eene se met en paix et la propage autour de lui, on ne transmet plus les ondes n\u00e9gatives que l\u2019on re\u00e7oit, on devient un catalyseur positif.<\/p>\n<p style=\"text-align: center;\">Un alchimiste capable de <strong>transmuter le plomb en Or<\/strong>, et on envoie autour de nous des ondes d\u2019amour et de s\u00e9r\u00e9nit\u00e9. Imaginez la vague d\u2019Amour et de paix que nous pourrons mettre en place dans les nouvelles \u00e9nergies de notre monde.<\/p>\n<p style=\"text-align: center;\"><strong>Alors oui, je souhaite que 2020, soit sous le signe de la paix en chacun de nous tous.<\/strong><\/p>\n<p style=\"text-align: right;\">Am\u00e9lie<\/p>\n<\/div><\/section><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4hrb1x-4c55ec24bc4f72df2f6b82864723ac02\">\n.flex_column.av-4hrb1x-4c55ec24bc4f72df2f6b82864723ac02{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-4hrb1x-4c55ec24bc4f72df2f6b82864723ac02 av_one_full  avia-builder-el-20  el_after_av_one_full  el_before_av_social_share  first flex_column_div av-zero-column-padding column-top-margin'   ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k56y3ikn-4d22348f2c379cf3e6091c6875b61b79\">\n.avia-image-container.av-k56y3ikn-4d22348f2c379cf3e6091c6875b61b79 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-k56y3ikn-4d22348f2c379cf3e6091c6875b61b79 av-styling- avia-align-center  avia-builder-el-21  avia-builder-el-no-sibling  '  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img class='wp-image-2217 avia-img-lazy-loading-not-2217 avia_image' src='https:\/\/joieinterieure.com\/wp-content\/uploads\/2020\/01\/Sans-titre-3-1030x1030.png' alt='Amour de soi' title='Prendre sa propre responsabilit\u00e9'  height=\"1030\" width=\"1030\"  itemprop=\"thumbnailUrl\"  \/><\/div><\/div><\/div><\/div>\n<div  class='av-social-sharing-box av-social-sharing-box-default   avia-builder-el-22  el_after_av_one_full  el_before_av_postslider  av-social-sharing-box-fullwidth '><div class=\"av-share-box\"><h5 class='av-share-link-description av-no-toc '>Partager cet article<\/h5><ul class=\"av-share-box-list noLightbox\"><li class='av-share-link av-social-link-facebook' ><a target=\"_blank\" aria-label=\"Partager sur Facebook\" href='https:\/\/www.facebook.com\/sharer.php?u=https:\/\/joieinterieure.com\/index.php\/2020\/01\/09\/devenir-responsable-de-soi\/&#038;t=Devenir%20responsable%20de%20soi' aria-hidden='false' data-av_icon='\ue8f3' data-av_iconfont='entypo-fontello' title='' data-avia-related-tooltip='Partager sur Facebook' rel=\"noopener\"><span class='avia_hidden_link_text'>Partager sur Facebook<\/span><\/a><\/li><li class='av-share-link av-social-link-twitter' ><a target=\"_blank\" aria-label=\"Partager sur Twitter\" href='https:\/\/twitter.com\/share?text=Devenir%20responsable%20de%20soi&#038;url=https:\/\/joieinterieure.com\/?p=2213' aria-hidden='false' data-av_icon='\ue8f1' data-av_iconfont='entypo-fontello' title='' data-avia-related-tooltip='Partager sur Twitter' rel=\"noopener\"><span class='avia_hidden_link_text'>Partager sur Twitter<\/span><\/a><\/li><li class='av-share-link av-social-link-whatsapp' ><a target=\"_blank\" aria-label=\"Partager sur WhatsApp\" href='https:\/\/api.whatsapp.com\/send?text=https:\/\/joieinterieure.com\/index.php\/2020\/01\/09\/devenir-responsable-de-soi\/' aria-hidden='false' data-av_icon='\uf232' data-av_iconfont='entypo-fontello' title='' data-avia-related-tooltip='Partager sur WhatsApp' rel=\"noopener\"><span class='avia_hidden_link_text'>Partager sur WhatsApp<\/span><\/a><\/li><li class='av-share-link av-social-link-pinterest' ><a target=\"_blank\" aria-label=\"Partager sur Pinterest\" href='https:\/\/pinterest.com\/pin\/create\/button\/?url=https%3A%2F%2Fjoieinterieure.com%2Findex.php%2F2020%2F01%2F09%2Fdevenir-responsable-de-soi%2F&#038;description=Devenir%20responsable%20de%20soi&#038;media=https%3A%2F%2Fjoieinterieure.com%2Fwp-content%2Fuploads%2F2020%2F01%2FSans-titre-3-705x705.png' aria-hidden='false' data-av_icon='\ue8f8' data-av_iconfont='entypo-fontello' title='' data-avia-related-tooltip='Partager sur Pinterest' rel=\"noopener\"><span class='avia_hidden_link_text'>Partager sur Pinterest<\/span><\/a><\/li><li class='av-share-link av-social-link-linkedin' ><a target=\"_blank\" aria-label=\"Partager sur LinkedIn\" href='https:\/\/linkedin.com\/shareArticle?mini=true&#038;title=Devenir%20responsable%20de%20soi&#038;url=https:\/\/joieinterieure.com\/index.php\/2020\/01\/09\/devenir-responsable-de-soi\/' aria-hidden='false' data-av_icon='\ue8fc' data-av_iconfont='entypo-fontello' title='' data-avia-related-tooltip='Partager sur LinkedIn' rel=\"noopener\"><span class='avia_hidden_link_text'>Partager sur LinkedIn<\/span><\/a><\/li><li class='av-share-link av-social-link-mail' ><a  aria-label=\"Partager par Mail\" href='mailto:?subject=Devenir%20responsable%20de%20soi&#038;body=https:\/\/joieinterieure.com\/index.php\/2020\/01\/09\/devenir-responsable-de-soi\/' aria-hidden='false' data-av_icon='\ue805' data-av_iconfont='entypo-fontello' title='' data-avia-related-tooltip='Partager par Mail'><span class='avia_hidden_link_text'>Partager par Mail<\/span><\/a><\/li><\/ul><\/div><\/div>\n<div   data-autoplay=''  data-interval='5'  data-animation='fade'  data-show_slide_delay='90'  class='avia-content-slider avia-content-slider-active avia-content-slider1 avia-content-slider-even  avia-builder-el-23  el_after_av_social_share  el_before_av_section  avia-builder-el-last  '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Blog\" ><div class='avia-content-slider-inner'><div class='slide-entry-wrap'><article class='slide-entry flex_column  post-entry post-entry-2293 slide-entry-overview slide-loop-1 slide-parity-odd  av_one_fourth first real-thumbnail post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><a href='https:\/\/joieinterieure.com\/index.php\/2020\/03\/26\/liberer-votre-esprit-de-toutes-pensees\/' data-rel='slide-1' class='slide-image' title='Lib\u00e9rer votre esprit de toutes pens\u00e9es'><img width=\"260\" height=\"185\" src=\"https:\/\/joieinterieure.com\/wp-content\/uploads\/2019\/01\/masaaki-komori-579102-unsplash-260x185.jpg\" class=\"wp-image-524 avia-img-lazy-loading-not-524 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"\" \/><\/a><div class='slide-content'><header class=\"entry-content-header\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/joieinterieure.com\/index.php\/category\/spiritualite\/\" rel=\"tag\">Spiritualit\u00e9<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/joieinterieure.com\/index.php\/2020\/03\/26\/liberer-votre-esprit-de-toutes-pensees\/' title='Lib\u00e9rer votre esprit de toutes pens\u00e9es'>Lib\u00e9rer votre esprit de toutes pens\u00e9es<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" >Ressentir ses pens\u00e9es et se reconnecter \u00e0 sa conscience gr\u00e2ce \u00e0 un exercice facile et rapide \u00e0 exp\u00e9rimenter en quelques minutes. <\/div><\/div><footer class=\"entry-footer\"><div class='slide-meta'><div class='slide-meta-comments'><a href='https:\/\/joieinterieure.com\/index.php\/2020\/03\/26\/liberer-votre-esprit-de-toutes-pensees\/#respond'>0 Commentaires<\/a><\/div><div class='slide-meta-del'>\/<\/div><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2020-03-26T17:08:09+01:00\" >26 mars 2020<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/joieinterieure.com\/wp-content\/uploads\/2019\/01\/masaaki-komori-579102-unsplash.jpg<\/span>\n\t\t\t\t\t\t<span itemprop='height'>4016<\/span>\n\t\t\t\t\t\t<span itemprop='width'>6016<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>Am\u00e9lie<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/joieinterieure.com\/wp-content\/uploads\/2020\/07\/logo-ad-small.png<\/span>\n\t\t\t\t\t\t <\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>Am\u00e9lie<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2020-01-09T17:38:02+01:00\" >2020-03-26 17:08:09<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2020-03-26 17:34:35<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Lib\u00e9rer votre esprit de toutes pens\u00e9es<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-2242 slide-entry-overview slide-loop-2 slide-parity-even  av_one_fourth  real-thumbnail post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><a href='https:\/\/joieinterieure.com\/index.php\/2020\/01\/22\/le-tarot-psychologique-kesako\/' data-rel='slide-1' class='slide-image' title='Le Tarot Psychologique kesako ?'><img width=\"260\" height=\"185\" src=\"https:\/\/joieinterieure.com\/wp-content\/uploads\/2020\/01\/LE-TAROT-260x185.png\" class=\"wp-image-2243 avia-img-lazy-loading-not-2243 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"tarot psychologique\" \/><small class='avia-copyright'>tarot<\/small><\/a><div class='slide-content'><header class=\"entry-content-header\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/joieinterieure.com\/index.php\/category\/spiritualite\/\" rel=\"tag\">Spiritualit\u00e9<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/joieinterieure.com\/index.php\/2020\/01\/22\/le-tarot-psychologique-kesako\/' title='Le Tarot Psychologique kesako ?'>Le Tarot Psychologique kesako ?<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" >Le tarot psychologique est un outil de connaissance de soi afin d'y voir plus clair sur notre chemin pr\u00e9sent. Il n'est pas question de voyance mais de clarification sur une situation. <\/div><\/div><footer class=\"entry-footer\"><div class='slide-meta'><div class='slide-meta-comments'><a href='https:\/\/joieinterieure.com\/index.php\/2020\/01\/22\/le-tarot-psychologique-kesako\/#respond'>0 Commentaires<\/a><\/div><div class='slide-meta-del'>\/<\/div><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2020-01-22T16:17:51+01:00\" >22 janvier 2020<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/joieinterieure.com\/wp-content\/uploads\/2020\/01\/LE-TAROT.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>1080<\/span>\n\t\t\t\t\t\t<span itemprop='width'>1080<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>Am\u00e9lie<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/joieinterieure.com\/wp-content\/uploads\/2020\/07\/logo-ad-small.png<\/span>\n\t\t\t\t\t\t <\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>Am\u00e9lie<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2020-01-09T17:38:02+01:00\" >2020-01-22 16:17:51<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2020-03-06 14:18:29<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Le Tarot Psychologique kesako ?<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-2213 slide-entry-overview slide-loop-3 slide-parity-odd  av_one_fourth  real-thumbnail post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><a href='https:\/\/joieinterieure.com\/index.php\/2020\/01\/09\/devenir-responsable-de-soi\/' data-rel='slide-1' class='slide-image' title='Devenir responsable de soi'><img width=\"260\" height=\"185\" src=\"https:\/\/joieinterieure.com\/wp-content\/uploads\/2020\/01\/Sans-titre-3-260x185.png\" class=\"wp-image-2217 avia-img-lazy-loading-not-2217 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"Amour de soi\" \/><small class='avia-copyright'>amour de soi<\/small><\/a><div class='slide-content'><header class=\"entry-content-header\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/joieinterieure.com\/index.php\/category\/spiritualite\/\" rel=\"tag\">Spiritualit\u00e9<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/joieinterieure.com\/index.php\/2020\/01\/09\/devenir-responsable-de-soi\/' title='Devenir responsable de soi'>Devenir responsable de soi<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" >Devenir responsable de soi est le plus beau cadeau que l\u2019on peut offrir \u00e0 la plan\u00e8te, au monde et \u00e0 nous-m\u00eame. Si nous ne sommes pas en paix \u00e0 l\u2019int\u00e9rieur nos interventions ext\u00e9rieures ne seront pas g\u00e9n\u00e9ratrices de notre volont\u00e9 originelle.<\/div><\/div><footer class=\"entry-footer\"><div class='slide-meta'><div class='slide-meta-comments'><a href='https:\/\/joieinterieure.com\/index.php\/2020\/01\/09\/devenir-responsable-de-soi\/#respond'>0 Commentaires<\/a><\/div><div class='slide-meta-del'>\/<\/div><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2020-01-09T17:38:02+01:00\" >9 janvier 2020<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/joieinterieure.com\/wp-content\/uploads\/2020\/01\/Sans-titre-3.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>1080<\/span>\n\t\t\t\t\t\t<span itemprop='width'>1080<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>Am\u00e9lie<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/joieinterieure.com\/wp-content\/uploads\/2020\/07\/logo-ad-small.png<\/span>\n\t\t\t\t\t\t <\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>Am\u00e9lie<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2020-01-09T17:38:02+01:00\" >2020-01-09 17:38:02<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2020-01-13 16:15:55<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Devenir responsable de soi<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-2177 slide-entry-overview slide-loop-4 slide-parity-even  post-entry-last  av_one_fourth  real-thumbnail post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><a href='https:\/\/joieinterieure.com\/index.php\/2019\/11\/06\/la-trichotherapy-un-veritable-soin-energetique-a-travers-tes-cheveux\/' data-rel='slide-1' class='slide-image' title='La Trichotherapy, un v\u00e9ritable soin \u00e9nerg\u00e9tique \u00e0 travers tes cheveux'><img width=\"260\" height=\"185\" src=\"https:\/\/joieinterieure.com\/wp-content\/uploads\/2019\/11\/IMG_20191106_151647-260x185.jpg\" class=\"wp-image-2186 avia-img-lazy-loading-not-2186 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"Am\u00e9lie DUCROCQ Energ\u00e9ticienne\" \/><\/a><div class='slide-content'><header class=\"entry-content-header\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/joieinterieure.com\/index.php\/category\/spiritualite\/\" rel=\"tag\">Spiritualit\u00e9<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/joieinterieure.com\/index.php\/2019\/11\/06\/la-trichotherapy-un-veritable-soin-energetique-a-travers-tes-cheveux\/' title='La Trichotherapy, un v\u00e9ritable soin \u00e9nerg\u00e9tique \u00e0 travers tes cheveux'>La Trichotherapy, un v\u00e9ritable soin \u00e9nerg\u00e9tique \u00e0 travers tes cheveux<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" >L\u2019id\u00e9e de me faire couper les cheveux au sabre ne m\u2019a pas tout de suite s\u00e9duite de prime \u00e0 bord. Mais lorsque j'ai su qu\u2019il s\u2019agissait bien plus qu\u2019une simple coupe de cheveux, cela m\u2019a bien sur s\u00e9duite rapidement. Un v\u00e9ritable soin de l'\u00e2me. <\/div><\/div><footer class=\"entry-footer\"><div class='slide-meta'><div class='slide-meta-comments'><a href='https:\/\/joieinterieure.com\/index.php\/2019\/11\/06\/la-trichotherapy-un-veritable-soin-energetique-a-travers-tes-cheveux\/#comments'>1 Commentaire<\/a><\/div><div class='slide-meta-del'>\/<\/div><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2019-11-06T16:20:06+01:00\" >6 novembre 2019<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/joieinterieure.com\/wp-content\/uploads\/2019\/11\/IMG_20191106_151647.jpg<\/span>\n\t\t\t\t\t\t<span itemprop='height'>5632<\/span>\n\t\t\t\t\t\t<span itemprop='width'>4224<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>Am\u00e9lie<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/joieinterieure.com\/wp-content\/uploads\/2020\/07\/logo-ad-small.png<\/span>\n\t\t\t\t\t\t <\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>Am\u00e9lie<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2020-01-09T17:38:02+01:00\" >2019-11-06 16:20:06<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2020-01-09 20:39:09<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>La Trichotherapy, un v\u00e9ritable soin \u00e9nerg\u00e9tique \u00e0 travers tes cheveux<\/span><\/span><\/span><\/article><\/div><\/div><\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jpvcfn8a-3da0c108bc270e7dc7c27edb64435f4d\">\n.avia-section.av-jpvcfn8a-3da0c108bc270e7dc7c27edb64435f4d{\nbackground-color:rgba(237,222,199,0.49);\n}\n<\/style>\n<div id='av_section_2'  class='avia-section av-jpvcfn8a-3da0c108bc270e7dc7c27edb64435f4d main_color avia-section-default avia-no-border-styling  avia-builder-el-24  el_after_av_postslider  el_before_av_comments_list  avia-bg-style-scroll  container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-2213'><div class='entry-content-wrapper clearfix'>\n<div class='flex_column_table av-mz4e3-353a8906e953cd197be4ae5197d4465a sc-av_one_fourth av-equal-height-column-flextable'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mz4e3-353a8906e953cd197be4ae5197d4465a\">\n.flex_column.av-mz4e3-353a8906e953cd197be4ae5197d4465a{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-mz4e3-353a8906e953cd197be4ae5197d4465a av_one_fourth  avia-builder-el-25  el_before_av_three_fourth  avia-builder-el-first  first no_margin flex_column_table_cell av-equal-height-column av-align-middle av-zero-column-padding '   ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jqycvgra-a4bba60a7fce249f6dca4125d42d6a91\">\n.avia-image-container.av-jqycvgra-a4bba60a7fce249f6dca4125d42d6a91 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-jqycvgra-a4bba60a7fce249f6dca4125d42d6a91 av-styling- avia-align-center  avia-builder-el-26  avia-builder-el-no-sibling  '  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><a href=\"https:\/\/joieinterieure.com\/?page_id=758\" class='avia_image'  target=\"_blank\"  rel=\"noopener noreferrer\"><img class='wp-image-759 avia-img-lazy-loading-not-759 avia_image' src='https:\/\/joieinterieure.com\/wp-content\/uploads\/2019\/01\/Capture-d\u2019\u00e9cran-2019-01-15-\u00e0-15.32.58-184x300.png' alt='' title='Capture d\u2019\u00e9cran 2019-01-15 \u00e0 15.32.58'  itemprop=\"thumbnailUrl\"  \/><\/a><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-cznsz-20658a65ca7e10ae8bf9bdb5964accdc\">\n.flex_column.av-cznsz-20658a65ca7e10ae8bf9bdb5964accdc{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-cznsz-20658a65ca7e10ae8bf9bdb5964accdc av_three_fourth  avia-builder-el-27  el_after_av_one_fourth  avia-builder-el-last  no_margin flex_column_table_cell av-equal-height-column av-align-middle av-zero-column-padding '   ><section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock  '   itemprop=\"text\" ><h3>T\u00e9l\u00e9chargez\u00a0<strong>gratuitement<\/strong>\u00a0votre guide PDF<\/h3>\n<\/div><\/section><br \/>\n<section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock  '   itemprop=\"text\" ><p style=\"text-align: left;\">Je vous transmets aujourd\u2019hui ce guide afin de vous offrir quatre outils qui me semblent indispensables dans notre vie quotidienne :<\/p>\n<ul>\n<li><strong>Retrouver le calme int\u00e9rieur<\/strong>,<\/li>\n<li><strong>Augmenter votre taux vibratoire,<\/strong><\/li>\n<li><b>\u00c9quilibrer vos polarit\u00e9s,<\/b><\/li>\n<li><strong>Ainsi que prendre le temps de s\u2019Ancrer.<\/strong><\/li>\n<\/ul>\n<\/div><\/section><br \/>\n<\/p><\/div><\/div><!--close column table wrapper. Autoclose: 1 -->\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='after_section_2'  class='main_color av_default_container_wrap container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-2213'><div class='entry-content-wrapper clearfix'>\n<div  class='av-buildercomment av-2s086t-6164fb248a404549e42248d00c21319e '><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Devenir responsable de soi est le plus beau cadeau que l\u2019on peut offrir \u00e0 la plan\u00e8te, au monde et \u00e0 nous-m\u00eame. Si nous ne sommes pas en paix \u00e0 l\u2019int\u00e9rieur nos interventions ext\u00e9rieures ne seront pas g\u00e9n\u00e9ratrices de notre volont\u00e9 originelle.<\/p>\n","protected":false},"author":1,"featured_media":2217,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[14],"tags":[52,48,49,50,51],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Devenir responsable de soi - Joie Int\u00e9rieure<\/title>\n<meta name=\"description\" content=\"Devenir responsable de soi est le plus beau cadeau que l\u2019on peut offrir \u00e0 la plan\u00e8te, au monde et \u00e0 nous-m\u00eame. Si nous ne sommes pas en paix \u00e0 l\u2019int\u00e9rieur nos interventions ext\u00e9rieures ne seront pas g\u00e9n\u00e9ratrices de notre volont\u00e9 originelle.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/joieinterieure.com\/index.php\/2020\/01\/09\/devenir-responsable-de-soi\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Devenir responsable de soi - Joie Int\u00e9rieure\" \/>\n<meta property=\"og:description\" content=\"Devenir responsable de soi est le plus beau cadeau que l\u2019on peut offrir \u00e0 la plan\u00e8te, au monde et \u00e0 nous-m\u00eame. Si nous ne sommes pas en paix \u00e0 l\u2019int\u00e9rieur nos interventions ext\u00e9rieures ne seront pas g\u00e9n\u00e9ratrices de notre volont\u00e9 originelle.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/joieinterieure.com\/index.php\/2020\/01\/09\/devenir-responsable-de-soi\/\" \/>\n<meta property=\"og:site_name\" content=\"Joie Int\u00e9rieure\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-09T16:38:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-13T15:15:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/joieinterieure.com\/wp-content\/uploads\/2020\/01\/Sans-titre-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Am\u00e9lie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Am\u00e9lie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"19 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/joieinterieure.com\/index.php\/2020\/01\/09\/devenir-responsable-de-soi\/\",\"url\":\"https:\/\/joieinterieure.com\/index.php\/2020\/01\/09\/devenir-responsable-de-soi\/\",\"name\":\"Devenir responsable de soi - Joie Int\u00e9rieure\",\"isPartOf\":{\"@id\":\"https:\/\/joieinterieure.com\/#website\"},\"datePublished\":\"2020-01-09T16:38:02+00:00\",\"dateModified\":\"2020-01-13T15:15:55+00:00\",\"author\":{\"@id\":\"https:\/\/joieinterieure.com\/#\/schema\/person\/55320669fb1cf2f68be5dfc41563f376\"},\"description\":\"Devenir responsable de soi est le plus beau cadeau que l\u2019on peut offrir \u00e0 la plan\u00e8te, au monde et \u00e0 nous-m\u00eame. Si nous ne sommes pas en paix \u00e0 l\u2019int\u00e9rieur nos interventions ext\u00e9rieures ne seront pas g\u00e9n\u00e9ratrices de notre volont\u00e9 originelle.\",\"breadcrumb\":{\"@id\":\"https:\/\/joieinterieure.com\/index.php\/2020\/01\/09\/devenir-responsable-de-soi\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/joieinterieure.com\/index.php\/2020\/01\/09\/devenir-responsable-de-soi\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/joieinterieure.com\/index.php\/2020\/01\/09\/devenir-responsable-de-soi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/joieinterieure.com\/index.php\/acceuil-2020\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Devenir responsable de soi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/joieinterieure.com\/#website\",\"url\":\"https:\/\/joieinterieure.com\/\",\"name\":\"Joie Int\u00e9rieure\",\"description\":\"Am\u00e9lie Ducrocq\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/joieinterieure.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/joieinterieure.com\/#\/schema\/person\/55320669fb1cf2f68be5dfc41563f376\",\"name\":\"Am\u00e9lie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/joieinterieure.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/741c67c54f2bcc0050f52da67dbe125a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/741c67c54f2bcc0050f52da67dbe125a?s=96&d=mm&r=g\",\"caption\":\"Am\u00e9lie\"},\"sameAs\":[\"https:\/\/joieinterieure.com\/\"],\"url\":\"https:\/\/joieinterieure.com\/index.php\/author\/admin6862\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Devenir responsable de soi - Joie Int\u00e9rieure","description":"Devenir responsable de soi est le plus beau cadeau que l\u2019on peut offrir \u00e0 la plan\u00e8te, au monde et \u00e0 nous-m\u00eame. Si nous ne sommes pas en paix \u00e0 l\u2019int\u00e9rieur nos interventions ext\u00e9rieures ne seront pas g\u00e9n\u00e9ratrices de notre volont\u00e9 originelle.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/joieinterieure.com\/index.php\/2020\/01\/09\/devenir-responsable-de-soi\/","og_locale":"fr_FR","og_type":"article","og_title":"Devenir responsable de soi - Joie Int\u00e9rieure","og_description":"Devenir responsable de soi est le plus beau cadeau que l\u2019on peut offrir \u00e0 la plan\u00e8te, au monde et \u00e0 nous-m\u00eame. Si nous ne sommes pas en paix \u00e0 l\u2019int\u00e9rieur nos interventions ext\u00e9rieures ne seront pas g\u00e9n\u00e9ratrices de notre volont\u00e9 originelle.","og_url":"https:\/\/joieinterieure.com\/index.php\/2020\/01\/09\/devenir-responsable-de-soi\/","og_site_name":"Joie Int\u00e9rieure","article_published_time":"2020-01-09T16:38:02+00:00","article_modified_time":"2020-01-13T15:15:55+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/joieinterieure.com\/wp-content\/uploads\/2020\/01\/Sans-titre-3.png","type":"image\/png"}],"author":"Am\u00e9lie","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Am\u00e9lie","Dur\u00e9e de lecture estim\u00e9e":"19 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/joieinterieure.com\/index.php\/2020\/01\/09\/devenir-responsable-de-soi\/","url":"https:\/\/joieinterieure.com\/index.php\/2020\/01\/09\/devenir-responsable-de-soi\/","name":"Devenir responsable de soi - Joie Int\u00e9rieure","isPartOf":{"@id":"https:\/\/joieinterieure.com\/#website"},"datePublished":"2020-01-09T16:38:02+00:00","dateModified":"2020-01-13T15:15:55+00:00","author":{"@id":"https:\/\/joieinterieure.com\/#\/schema\/person\/55320669fb1cf2f68be5dfc41563f376"},"description":"Devenir responsable de soi est le plus beau cadeau que l\u2019on peut offrir \u00e0 la plan\u00e8te, au monde et \u00e0 nous-m\u00eame. Si nous ne sommes pas en paix \u00e0 l\u2019int\u00e9rieur nos interventions ext\u00e9rieures ne seront pas g\u00e9n\u00e9ratrices de notre volont\u00e9 originelle.","breadcrumb":{"@id":"https:\/\/joieinterieure.com\/index.php\/2020\/01\/09\/devenir-responsable-de-soi\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/joieinterieure.com\/index.php\/2020\/01\/09\/devenir-responsable-de-soi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/joieinterieure.com\/index.php\/2020\/01\/09\/devenir-responsable-de-soi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/joieinterieure.com\/index.php\/acceuil-2020\/"},{"@type":"ListItem","position":2,"name":"Devenir responsable de soi"}]},{"@type":"WebSite","@id":"https:\/\/joieinterieure.com\/#website","url":"https:\/\/joieinterieure.com\/","name":"Joie Int\u00e9rieure","description":"Am\u00e9lie Ducrocq","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/joieinterieure.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/joieinterieure.com\/#\/schema\/person\/55320669fb1cf2f68be5dfc41563f376","name":"Am\u00e9lie","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/joieinterieure.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/741c67c54f2bcc0050f52da67dbe125a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/741c67c54f2bcc0050f52da67dbe125a?s=96&d=mm&r=g","caption":"Am\u00e9lie"},"sameAs":["https:\/\/joieinterieure.com\/"],"url":"https:\/\/joieinterieure.com\/index.php\/author\/admin6862\/"}]}},"_links":{"self":[{"href":"https:\/\/joieinterieure.com\/index.php\/wp-json\/wp\/v2\/posts\/2213"}],"collection":[{"href":"https:\/\/joieinterieure.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/joieinterieure.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/joieinterieure.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/joieinterieure.com\/index.php\/wp-json\/wp\/v2\/comments?post=2213"}],"version-history":[{"count":16,"href":"https:\/\/joieinterieure.com\/index.php\/wp-json\/wp\/v2\/posts\/2213\/revisions"}],"predecessor-version":[{"id":2240,"href":"https:\/\/joieinterieure.com\/index.php\/wp-json\/wp\/v2\/posts\/2213\/revisions\/2240"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/joieinterieure.com\/index.php\/wp-json\/wp\/v2\/media\/2217"}],"wp:attachment":[{"href":"https:\/\/joieinterieure.com\/index.php\/wp-json\/wp\/v2\/media?parent=2213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/joieinterieure.com\/index.php\/wp-json\/wp\/v2\/categories?post=2213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/joieinterieure.com\/index.php\/wp-json\/wp\/v2\/tags?post=2213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}